{"id":1470,"count":10,"description":"American Pan a en stock des plaques \u00e0 Pizza lisses et perfor\u00e9es. Si vous ne trouvez pas le style que vous recherchez, contactez-nous pour un devis personnalis\u00e9.","link":"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/plaques-a-pizza\/","name":"Plaques \u00e0 Pizza","slug":"plaques-a-pizza","taxonomy":"product_cat","parent":1375,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Plaques \u00e0 Pizza &#8902; American Pan Europe<\/title>\n<meta name=\"description\" content=\"American Pan a en stock des plaques \u00e0 Pizza lisses et perfor\u00e9es. Si vous ne trouvez pas le style que vous recherchez, contactez-nous pour un devis personnalis\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/plaques-a-pizza\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plaques \u00e0 Pizza &#8902; American Pan Europe\" \/>\n<meta property=\"og:description\" content=\"American Pan a en stock des plaques \u00e0 Pizza lisses et perfor\u00e9es. Si vous ne trouvez pas le style que vous recherchez, contactez-nous pour un devis personnalis\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/plaques-a-pizza\/\" \/>\n<meta property=\"og:site_name\" content=\"American Pan Europe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/product-category\\\/moules-et-plaques-de-cuisson-en-stock\\\/plaques-a-pizza\\\/\",\"url\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/product-category\\\/moules-et-plaques-de-cuisson-en-stock\\\/plaques-a-pizza\\\/\",\"name\":\"Plaques \u00e0 Pizza &#8902; American Pan Europe\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/#website\"},\"description\":\"American Pan a en stock des plaques \u00e0 Pizza lisses et perfor\u00e9es. Si vous ne trouvez pas le style que vous recherchez, contactez-nous pour un devis personnalis\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/product-category\\\/moules-et-plaques-de-cuisson-en-stock\\\/plaques-a-pizza\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/product-category\\\/moules-et-plaques-de-cuisson-en-stock\\\/plaques-a-pizza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moules et plaques de cuisson en stock\",\"item\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/product-category\\\/moules-et-plaques-de-cuisson-en-stock\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plaques \u00e0 Pizza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/\",\"name\":\"American Pan Europe\",\"description\":\"Moules et Rev\u00eatements Industriels\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/#organization\",\"name\":\"American Pan: Moules et Rev\u00eatements Industriels\",\"url\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2022\\\/03\\\/logo-europe.png\",\"contentUrl\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2022\\\/03\\\/logo-europe.png\",\"width\":458,\"height\":172,\"caption\":\"American Pan: Moules et Rev\u00eatements Industriels\"},\"image\":{\"@id\":\"https:\\\/\\\/www.americanpan.com\\\/europe\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plaques \u00e0 Pizza &#8902; American Pan Europe","description":"American Pan a en stock des plaques \u00e0 Pizza lisses et perfor\u00e9es. Si vous ne trouvez pas le style que vous recherchez, contactez-nous pour un devis personnalis\u00e9.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/plaques-a-pizza\/","og_locale":"fr_FR","og_type":"article","og_title":"Plaques \u00e0 Pizza &#8902; American Pan Europe","og_description":"American Pan a en stock des plaques \u00e0 Pizza lisses et perfor\u00e9es. Si vous ne trouvez pas le style que vous recherchez, contactez-nous pour un devis personnalis\u00e9.","og_url":"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/plaques-a-pizza\/","og_site_name":"American Pan Europe","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/plaques-a-pizza\/","url":"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/plaques-a-pizza\/","name":"Plaques \u00e0 Pizza &#8902; American Pan Europe","isPartOf":{"@id":"https:\/\/www.americanpan.com\/europe\/fr\/#website"},"description":"American Pan a en stock des plaques \u00e0 Pizza lisses et perfor\u00e9es. Si vous ne trouvez pas le style que vous recherchez, contactez-nous pour un devis personnalis\u00e9.","breadcrumb":{"@id":"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/plaques-a-pizza\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/plaques-a-pizza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.americanpan.com\/europe\/fr\/"},{"@type":"ListItem","position":2,"name":"Moules et plaques de cuisson en stock","item":"https:\/\/www.americanpan.com\/europe\/fr\/product-category\/moules-et-plaques-de-cuisson-en-stock\/"},{"@type":"ListItem","position":3,"name":"Plaques \u00e0 Pizza"}]},{"@type":"WebSite","@id":"https:\/\/www.americanpan.com\/europe\/fr\/#website","url":"https:\/\/www.americanpan.com\/europe\/fr\/","name":"American Pan Europe","description":"Moules et Rev\u00eatements Industriels","publisher":{"@id":"https:\/\/www.americanpan.com\/europe\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.americanpan.com\/europe\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.americanpan.com\/europe\/fr\/#organization","name":"American Pan: Moules et Rev\u00eatements Industriels","url":"https:\/\/www.americanpan.com\/europe\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.americanpan.com\/europe\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.americanpan.com\/europe\/wp-content\/uploads\/sites\/18\/2022\/03\/logo-europe.png","contentUrl":"https:\/\/www.americanpan.com\/europe\/wp-content\/uploads\/sites\/18\/2022\/03\/logo-europe.png","width":458,"height":172,"caption":"American Pan: Moules et Rev\u00eatements Industriels"},"image":{"@id":"https:\/\/www.americanpan.com\/europe\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.americanpan.com\/europe\/fr\/wp-json\/wp\/v2\/product_cat\/1470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.americanpan.com\/europe\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.americanpan.com\/europe\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.americanpan.com\/europe\/fr\/wp-json\/wp\/v2\/product_cat\/1375"}],"wp:post_type":[{"href":"https:\/\/www.americanpan.com\/europe\/fr\/wp-json\/wp\/v2\/product?product_cat=1470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}